{"id":36672,"date":"2021-08-06T09:14:02","date_gmt":"2021-08-06T07:14:02","guid":{"rendered":"https:\/\/extebois.fr\/produit\/uncategorized\/climbing-wall-ladder-metal\/"},"modified":"2026-08-28T09:06:02","modified_gmt":"2026-08-28T07:06:02","slug":"climbing-wall-ladder-metal","status":"publish","type":"product","link":"https:\/\/extebois.fr\/en\/extebois-les-produits\/sport-en\/metal-mini-course-en\/climbing-wall-ladder-metal\/","title":{"rendered":"CLIMBING WALL + LADDER METAL"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":45477,"template":"","meta":[],"product_brand":[],"product_cat":[137],"product_tag":[],"class_list":["post-36672","product","type-product","status-publish","has-post-thumbnail","product_cat-metal-mini-course-en","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CLIMBING WALL + LADDER METAL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/extebois.fr\/en\/extebois-les-produits\/sport-en\/metal-mini-course-en\/climbing-wall-ladder-metal\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CLIMBING WALL + LADDER METAL\" \/>\n<meta property=\"og:url\" content=\"https:\/\/extebois.fr\/en\/extebois-les-produits\/sport-en\/metal-mini-course-en\/climbing-wall-ladder-metal\/\" \/>\n<meta property=\"og:site_name\" content=\"EXTEBOIS\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-28T07:06:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2021\/08\/Capture3D1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"333\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/sport-en\\\/metal-mini-course-en\\\/climbing-wall-ladder-metal\\\/\",\"url\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/sport-en\\\/metal-mini-course-en\\\/climbing-wall-ladder-metal\\\/\",\"name\":\"CLIMBING WALL + LADDER METAL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/sport-en\\\/metal-mini-course-en\\\/climbing-wall-ladder-metal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/sport-en\\\/metal-mini-course-en\\\/climbing-wall-ladder-metal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/extebois.fr\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Capture3D1.jpg\",\"datePublished\":\"2021-08-06T07:14:02+00:00\",\"dateModified\":\"2026-08-28T07:06:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/sport-en\\\/metal-mini-course-en\\\/climbing-wall-ladder-metal\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/sport-en\\\/metal-mini-course-en\\\/climbing-wall-ladder-metal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/sport-en\\\/metal-mini-course-en\\\/climbing-wall-ladder-metal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/extebois.fr\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Capture3D1.jpg\",\"contentUrl\":\"https:\\\/\\\/extebois.fr\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Capture3D1.jpg\",\"width\":333,\"height\":534},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/sport-en\\\/metal-mini-course-en\\\/climbing-wall-ladder-metal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/extebois.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ext\u00e9bois-Les produits\",\"item\":\"https:\\\/\\\/extebois.fr\\\/extebois-les-produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sport\",\"item\":\"https:\\\/\\\/extebois.fr\\\/en\\\/products\\\/sport-en\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Metal mini-course\",\"item\":\"https:\\\/\\\/extebois.fr\\\/en\\\/products\\\/sport-en\\\/metal-mini-course-en\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"CLIMBING WALL + LADDER METAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/extebois.fr\\\/en\\\/\",\"name\":\"EXTEBOIS\",\"description\":\"Cr\u00e9ateur d&#039;\u00e9quipements ludiques et sportifs\",\"publisher\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/extebois.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#organization\",\"name\":\"Ext\u00e9bois\",\"url\":\"https:\\\/\\\/extebois.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/extebois.fr\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/extebois-logo-gris.png\",\"contentUrl\":\"https:\\\/\\\/extebois.fr\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/extebois-logo-gris.png\",\"width\":189,\"height\":52,\"caption\":\"Ext\u00e9bois\"},\"image\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CLIMBING WALL + LADDER METAL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/extebois.fr\/en\/extebois-les-produits\/sport-en\/metal-mini-course-en\/climbing-wall-ladder-metal\/","og_locale":"en_US","og_type":"article","og_title":"CLIMBING WALL + LADDER METAL","og_url":"https:\/\/extebois.fr\/en\/extebois-les-produits\/sport-en\/metal-mini-course-en\/climbing-wall-ladder-metal\/","og_site_name":"EXTEBOIS","article_modified_time":"2026-08-28T07:06:02+00:00","og_image":[{"width":333,"height":534,"url":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2021\/08\/Capture3D1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/sport-en\/metal-mini-course-en\/climbing-wall-ladder-metal\/","url":"https:\/\/extebois.fr\/en\/extebois-les-produits\/sport-en\/metal-mini-course-en\/climbing-wall-ladder-metal\/","name":"CLIMBING WALL + LADDER METAL","isPartOf":{"@id":"https:\/\/extebois.fr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/sport-en\/metal-mini-course-en\/climbing-wall-ladder-metal\/#primaryimage"},"image":{"@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/sport-en\/metal-mini-course-en\/climbing-wall-ladder-metal\/#primaryimage"},"thumbnailUrl":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2021\/08\/Capture3D1.jpg","datePublished":"2021-08-06T07:14:02+00:00","dateModified":"2026-08-28T07:06:02+00:00","breadcrumb":{"@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/sport-en\/metal-mini-course-en\/climbing-wall-ladder-metal\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/extebois.fr\/en\/extebois-les-produits\/sport-en\/metal-mini-course-en\/climbing-wall-ladder-metal\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/sport-en\/metal-mini-course-en\/climbing-wall-ladder-metal\/#primaryimage","url":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2021\/08\/Capture3D1.jpg","contentUrl":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2021\/08\/Capture3D1.jpg","width":333,"height":534},{"@type":"BreadcrumbList","@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/sport-en\/metal-mini-course-en\/climbing-wall-ladder-metal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/extebois.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Ext\u00e9bois-Les produits","item":"https:\/\/extebois.fr\/extebois-les-produits\/"},{"@type":"ListItem","position":3,"name":"Sport","item":"https:\/\/extebois.fr\/en\/products\/sport-en\/"},{"@type":"ListItem","position":4,"name":"Metal mini-course","item":"https:\/\/extebois.fr\/en\/products\/sport-en\/metal-mini-course-en\/"},{"@type":"ListItem","position":5,"name":"CLIMBING WALL + LADDER METAL"}]},{"@type":"WebSite","@id":"https:\/\/extebois.fr\/en\/#website","url":"https:\/\/extebois.fr\/en\/","name":"EXTEBOIS","description":"Cr\u00e9ateur d&#039;\u00e9quipements ludiques et sportifs","publisher":{"@id":"https:\/\/extebois.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/extebois.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/extebois.fr\/en\/#organization","name":"Ext\u00e9bois","url":"https:\/\/extebois.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/extebois.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2020\/10\/extebois-logo-gris.png","contentUrl":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2020\/10\/extebois-logo-gris.png","width":189,"height":52,"caption":"Ext\u00e9bois"},"image":{"@id":"https:\/\/extebois.fr\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product\/36672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/media\/45477"}],"wp:attachment":[{"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/media?parent=36672"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product_brand?post=36672"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product_cat?post=36672"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product_tag?post=36672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}