{"id":37801,"date":"2020-12-17T16:49:49","date_gmt":"2020-12-17T15:49:49","guid":{"rendered":"https:\/\/extebois.fr\/produit\/uncategorized\/tree-p4000\/"},"modified":"2026-02-20T10:43:17","modified_gmt":"2026-02-20T09:43:17","slug":"arbre-p4000","status":"publish","type":"product","link":"https:\/\/extebois.fr\/en\/extebois-les-produits\/trees-en\/arbre-p4000\/","title":{"rendered":"ARBRE P4000"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":60226,"template":"","meta":[],"product_brand":[],"product_cat":[100],"product_tag":[228,227],"class_list":["post-37801","product","type-product","status-publish","has-post-thumbnail","product_cat-trees-en","product_tag-inclusive","product_tag-nature-en","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ARBRE P4000<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/extebois.fr\/en\/extebois-les-produits\/trees-en\/arbre-p4000\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ARBRE P4000\" \/>\n<meta property=\"og:url\" content=\"https:\/\/extebois.fr\/en\/extebois-les-produits\/trees-en\/arbre-p4000\/\" \/>\n<meta property=\"og:site_name\" content=\"EXTEBOIS\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-20T09:43:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2020\/12\/MX-ARB-P4000-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/trees-en\\\/arbre-p4000\\\/\",\"url\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/trees-en\\\/arbre-p4000\\\/\",\"name\":\"ARBRE P4000\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/trees-en\\\/arbre-p4000\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/trees-en\\\/arbre-p4000\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/extebois.fr\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/MX-ARB-P4000-2-scaled.jpg\",\"datePublished\":\"2020-12-17T15:49:49+00:00\",\"dateModified\":\"2026-02-20T09:43:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/trees-en\\\/arbre-p4000\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/trees-en\\\/arbre-p4000\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/trees-en\\\/arbre-p4000\\\/#primaryimage\",\"url\":\"https:\\\/\\\/extebois.fr\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/MX-ARB-P4000-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/extebois.fr\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/MX-ARB-P4000-2-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/trees-en\\\/arbre-p4000\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/extebois.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ext\u00e9bois-Les produits\",\"item\":\"https:\\\/\\\/extebois.fr\\\/extebois-les-produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Arbres\",\"item\":\"https:\\\/\\\/extebois.fr\\\/en\\\/products\\\/trees-en\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"ARBRE P4000\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/extebois.fr\\\/en\\\/\",\"name\":\"EXTEBOIS\",\"description\":\"Cr\u00e9ateur d&#039;\u00e9quipements ludiques et sportifs\",\"publisher\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/extebois.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#organization\",\"name\":\"Ext\u00e9bois\",\"url\":\"https:\\\/\\\/extebois.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/extebois.fr\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/extebois-logo-gris.png\",\"contentUrl\":\"https:\\\/\\\/extebois.fr\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/extebois-logo-gris.png\",\"width\":189,\"height\":52,\"caption\":\"Ext\u00e9bois\"},\"image\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ARBRE P4000","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/extebois.fr\/en\/extebois-les-produits\/trees-en\/arbre-p4000\/","og_locale":"en_US","og_type":"article","og_title":"ARBRE P4000","og_url":"https:\/\/extebois.fr\/en\/extebois-les-produits\/trees-en\/arbre-p4000\/","og_site_name":"EXTEBOIS","article_modified_time":"2026-02-20T09:43:17+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2020\/12\/MX-ARB-P4000-2-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/trees-en\/arbre-p4000\/","url":"https:\/\/extebois.fr\/en\/extebois-les-produits\/trees-en\/arbre-p4000\/","name":"ARBRE P4000","isPartOf":{"@id":"https:\/\/extebois.fr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/trees-en\/arbre-p4000\/#primaryimage"},"image":{"@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/trees-en\/arbre-p4000\/#primaryimage"},"thumbnailUrl":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2020\/12\/MX-ARB-P4000-2-scaled.jpg","datePublished":"2020-12-17T15:49:49+00:00","dateModified":"2026-02-20T09:43:17+00:00","breadcrumb":{"@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/trees-en\/arbre-p4000\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/extebois.fr\/en\/extebois-les-produits\/trees-en\/arbre-p4000\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/trees-en\/arbre-p4000\/#primaryimage","url":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2020\/12\/MX-ARB-P4000-2-scaled.jpg","contentUrl":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2020\/12\/MX-ARB-P4000-2-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/trees-en\/arbre-p4000\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/extebois.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Ext\u00e9bois-Les produits","item":"https:\/\/extebois.fr\/extebois-les-produits\/"},{"@type":"ListItem","position":3,"name":"Arbres","item":"https:\/\/extebois.fr\/en\/products\/trees-en\/"},{"@type":"ListItem","position":4,"name":"ARBRE P4000"}]},{"@type":"WebSite","@id":"https:\/\/extebois.fr\/en\/#website","url":"https:\/\/extebois.fr\/en\/","name":"EXTEBOIS","description":"Cr\u00e9ateur d&#039;\u00e9quipements ludiques et sportifs","publisher":{"@id":"https:\/\/extebois.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/extebois.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/extebois.fr\/en\/#organization","name":"Ext\u00e9bois","url":"https:\/\/extebois.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/extebois.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2020\/10\/extebois-logo-gris.png","contentUrl":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2020\/10\/extebois-logo-gris.png","width":189,"height":52,"caption":"Ext\u00e9bois"},"image":{"@id":"https:\/\/extebois.fr\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product\/37801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/media\/60226"}],"wp:attachment":[{"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/media?parent=37801"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product_brand?post=37801"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product_cat?post=37801"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product_tag?post=37801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}