{"id":41857,"date":"2022-03-08T15:11:05","date_gmt":"2022-03-08T14:11:05","guid":{"rendered":"https:\/\/extebois.fr\/produit\/uncategorized\/hyla-the-frog\/"},"modified":"2026-03-17T09:47:12","modified_gmt":"2026-03-17T08:47:12","slug":"hyla-the-frog","status":"publish","type":"product","link":"https:\/\/extebois.fr\/en\/extebois-les-produits\/the-classics-en\/spring-toys-en\/hyla-the-frog\/","title":{"rendered":"HYLA THE FROG"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":32232,"template":"","meta":[],"product_brand":[],"product_cat":[127],"product_tag":[],"class_list":{"0":"post-41857","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-spring-toys-en","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HYLA THE FROG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/extebois.fr\/en\/extebois-les-produits\/the-classics-en\/spring-toys-en\/hyla-the-frog\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HYLA THE FROG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/extebois.fr\/en\/extebois-les-produits\/the-classics-en\/spring-toys-en\/hyla-the-frog\/\" \/>\n<meta property=\"og:site_name\" content=\"EXTEBOIS\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-17T08:47:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2022\/03\/JR169-vue-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1978\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/the-classics-en\\\/spring-toys-en\\\/hyla-the-frog\\\/\",\"url\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/the-classics-en\\\/spring-toys-en\\\/hyla-the-frog\\\/\",\"name\":\"HYLA THE FROG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/the-classics-en\\\/spring-toys-en\\\/hyla-the-frog\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/the-classics-en\\\/spring-toys-en\\\/hyla-the-frog\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/extebois.fr\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/JR169-vue-1-scaled.jpg\",\"datePublished\":\"2022-03-08T14:11:05+00:00\",\"dateModified\":\"2026-03-17T08:47:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/the-classics-en\\\/spring-toys-en\\\/hyla-the-frog\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/the-classics-en\\\/spring-toys-en\\\/hyla-the-frog\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/the-classics-en\\\/spring-toys-en\\\/hyla-the-frog\\\/#primaryimage\",\"url\":\"https:\\\/\\\/extebois.fr\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/JR169-vue-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/extebois.fr\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/JR169-vue-1-scaled.jpg\",\"width\":2560,\"height\":1978},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/extebois-les-produits\\\/the-classics-en\\\/spring-toys-en\\\/hyla-the-frog\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/extebois.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ext\u00e9bois-Les produits\",\"item\":\"https:\\\/\\\/extebois.fr\\\/extebois-les-produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The Classics\",\"item\":\"https:\\\/\\\/extebois.fr\\\/en\\\/products\\\/the-classics-en\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Spring toys\",\"item\":\"https:\\\/\\\/extebois.fr\\\/en\\\/products\\\/the-classics-en\\\/spring-toys-en\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"HYLA THE FROG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/extebois.fr\\\/en\\\/\",\"name\":\"EXTEBOIS\",\"description\":\"Cr\u00e9ateur d&#039;\u00e9quipements ludiques et sportifs\",\"publisher\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/extebois.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#organization\",\"name\":\"Ext\u00e9bois\",\"url\":\"https:\\\/\\\/extebois.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/extebois.fr\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/extebois-logo-gris.png\",\"contentUrl\":\"https:\\\/\\\/extebois.fr\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/extebois-logo-gris.png\",\"width\":189,\"height\":52,\"caption\":\"Ext\u00e9bois\"},\"image\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HYLA THE FROG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/extebois.fr\/en\/extebois-les-produits\/the-classics-en\/spring-toys-en\/hyla-the-frog\/","og_locale":"en_US","og_type":"article","og_title":"HYLA THE FROG","og_url":"https:\/\/extebois.fr\/en\/extebois-les-produits\/the-classics-en\/spring-toys-en\/hyla-the-frog\/","og_site_name":"EXTEBOIS","article_modified_time":"2026-03-17T08:47:12+00:00","og_image":[{"width":2560,"height":1978,"url":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2022\/03\/JR169-vue-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/the-classics-en\/spring-toys-en\/hyla-the-frog\/","url":"https:\/\/extebois.fr\/en\/extebois-les-produits\/the-classics-en\/spring-toys-en\/hyla-the-frog\/","name":"HYLA THE FROG","isPartOf":{"@id":"https:\/\/extebois.fr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/the-classics-en\/spring-toys-en\/hyla-the-frog\/#primaryimage"},"image":{"@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/the-classics-en\/spring-toys-en\/hyla-the-frog\/#primaryimage"},"thumbnailUrl":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2022\/03\/JR169-vue-1-scaled.jpg","datePublished":"2022-03-08T14:11:05+00:00","dateModified":"2026-03-17T08:47:12+00:00","breadcrumb":{"@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/the-classics-en\/spring-toys-en\/hyla-the-frog\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/extebois.fr\/en\/extebois-les-produits\/the-classics-en\/spring-toys-en\/hyla-the-frog\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/the-classics-en\/spring-toys-en\/hyla-the-frog\/#primaryimage","url":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2022\/03\/JR169-vue-1-scaled.jpg","contentUrl":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2022\/03\/JR169-vue-1-scaled.jpg","width":2560,"height":1978},{"@type":"BreadcrumbList","@id":"https:\/\/extebois.fr\/en\/extebois-les-produits\/the-classics-en\/spring-toys-en\/hyla-the-frog\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/extebois.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Ext\u00e9bois-Les produits","item":"https:\/\/extebois.fr\/extebois-les-produits\/"},{"@type":"ListItem","position":3,"name":"The Classics","item":"https:\/\/extebois.fr\/en\/products\/the-classics-en\/"},{"@type":"ListItem","position":4,"name":"Spring toys","item":"https:\/\/extebois.fr\/en\/products\/the-classics-en\/spring-toys-en\/"},{"@type":"ListItem","position":5,"name":"HYLA THE FROG"}]},{"@type":"WebSite","@id":"https:\/\/extebois.fr\/en\/#website","url":"https:\/\/extebois.fr\/en\/","name":"EXTEBOIS","description":"Cr\u00e9ateur d&#039;\u00e9quipements ludiques et sportifs","publisher":{"@id":"https:\/\/extebois.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/extebois.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/extebois.fr\/en\/#organization","name":"Ext\u00e9bois","url":"https:\/\/extebois.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/extebois.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2020\/10\/extebois-logo-gris.png","contentUrl":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2020\/10\/extebois-logo-gris.png","width":189,"height":52,"caption":"Ext\u00e9bois"},"image":{"@id":"https:\/\/extebois.fr\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product\/41857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/media\/32232"}],"wp:attachment":[{"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/media?parent=41857"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product_brand?post=41857"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product_cat?post=41857"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product_tag?post=41857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}