{"id":150,"count":3,"description":"","link":"https:\/\/extebois.fr\/en\/products\/sunny-en\/sunny-900-en\/","name":"Sunny 900","slug":"sunny-900-en","taxonomy":"product_cat","parent":149,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sunny 900 - EXTEBOIS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/extebois.fr\/en\/products\/sunny-en\/sunny-900-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sunny 900 - EXTEBOIS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/extebois.fr\/en\/products\/sunny-en\/sunny-900-en\/\" \/>\n<meta property=\"og:site_name\" content=\"EXTEBOIS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/products\\\/sunny-en\\\/sunny-900-en\\\/\",\"url\":\"https:\\\/\\\/extebois.fr\\\/en\\\/products\\\/sunny-en\\\/sunny-900-en\\\/\",\"name\":\"Sunny 900 - EXTEBOIS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/products\\\/sunny-en\\\/sunny-900-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/products\\\/sunny-en\\\/sunny-900-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/extebois.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ext\u00e9bois-Les produits\",\"item\":\"https:\\\/\\\/extebois.fr\\\/extebois-les-produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sunny\",\"item\":\"https:\\\/\\\/extebois.fr\\\/en\\\/products\\\/sunny-en\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Sunny 900\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/extebois.fr\\\/en\\\/\",\"name\":\"EXTEBOIS\",\"description\":\"Cr\u00e9ateur d&#039;\u00e9quipements ludiques et sportifs\",\"publisher\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/extebois.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#organization\",\"name\":\"Ext\u00e9bois\",\"url\":\"https:\\\/\\\/extebois.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/extebois.fr\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/extebois-logo-gris.png\",\"contentUrl\":\"https:\\\/\\\/extebois.fr\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/extebois-logo-gris.png\",\"width\":189,\"height\":52,\"caption\":\"Ext\u00e9bois\"},\"image\":{\"@id\":\"https:\\\/\\\/extebois.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sunny 900 - EXTEBOIS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/extebois.fr\/en\/products\/sunny-en\/sunny-900-en\/","og_locale":"en_US","og_type":"article","og_title":"Sunny 900 - EXTEBOIS","og_url":"https:\/\/extebois.fr\/en\/products\/sunny-en\/sunny-900-en\/","og_site_name":"EXTEBOIS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/extebois.fr\/en\/products\/sunny-en\/sunny-900-en\/","url":"https:\/\/extebois.fr\/en\/products\/sunny-en\/sunny-900-en\/","name":"Sunny 900 - EXTEBOIS","isPartOf":{"@id":"https:\/\/extebois.fr\/en\/#website"},"breadcrumb":{"@id":"https:\/\/extebois.fr\/en\/products\/sunny-en\/sunny-900-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/extebois.fr\/en\/products\/sunny-en\/sunny-900-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/extebois.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Ext\u00e9bois-Les produits","item":"https:\/\/extebois.fr\/extebois-les-produits\/"},{"@type":"ListItem","position":3,"name":"Sunny","item":"https:\/\/extebois.fr\/en\/products\/sunny-en\/"},{"@type":"ListItem","position":4,"name":"Sunny 900"}]},{"@type":"WebSite","@id":"https:\/\/extebois.fr\/en\/#website","url":"https:\/\/extebois.fr\/en\/","name":"EXTEBOIS","description":"Cr\u00e9ateur d&#039;\u00e9quipements ludiques et sportifs","publisher":{"@id":"https:\/\/extebois.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/extebois.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/extebois.fr\/en\/#organization","name":"Ext\u00e9bois","url":"https:\/\/extebois.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/extebois.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2020\/10\/extebois-logo-gris.png","contentUrl":"https:\/\/extebois.fr\/fr\/wp-content\/uploads\/2020\/10\/extebois-logo-gris.png","width":189,"height":52,"caption":"Ext\u00e9bois"},"image":{"@id":"https:\/\/extebois.fr\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product_cat\/150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product_cat\/149"}],"wp:post_type":[{"href":"https:\/\/extebois.fr\/en\/wp-json\/wp\/v2\/product?product_cat=150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}